{"id":1596,"date":"2016-01-07T09:30:26","date_gmt":"2016-01-07T08:30:26","guid":{"rendered":"http:\/\/yomecuidoyque.com\/?p=1596"},"modified":"2016-01-07T09:30:26","modified_gmt":"2016-01-07T08:30:26","slug":"10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos","status":"publish","type":"post","link":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/","title":{"rendered":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os"},"content":{"rendered":"<p><![CDATA[\n\n<h2 style=\"text-align: justify;\">Adi\u00f3s excesos,\u00a0 bienvenida dieta sana<\/h2>\n\n\n\n\n<p style=\"text-align: justify;\">Despu\u00e9s de los excesos navide\u00f1os, es normal sentir cierto malestar; hinchaz\u00f3n, empacho, diarrea, estre\u00f1imiento, dolor de cabeza, aumento de peso\u2026provocado por el cambio de alimentaci\u00f3n en estos d\u00edas, grandes comilonas con una cantidad elevada de grasas y az\u00facares, ingesta de alcohol y abandono de los h\u00e1bitos saludables.\nTras todos estos excesos es muy com\u00fan tomar como referencia dietas restrictivas, que solo nos permiten ingerir un alimento o nos limitan el consumo de nutrientes. Es un error tomar estas \u201ccuras depurativas\u201d como dietas de adelgazamiento, pues esa no es su finalidad y no pueden prolongarse en el tiempo. Los kilos que se pierden, se recuperan f\u00e1cilmente.\nEn cambio, puede ser un buen momento para retomar o adquirir h\u00e1bitos saludables; una alimentaci\u00f3n adecuada, ejercicio 30-40 minutos diarios y abandonar h\u00e1bitos t\u00f3xicos como el alcohol o el tabaco.\nPara ello debemos fijar nuestro objetivo nutricional en comidas m\u00e1s ligeras y nutritivas que nos ayuden a eliminar l\u00edquidos y toxinas, favoreciendo una bajada de peso y reducci\u00f3n de la hinchaz\u00f3n.<\/p>\n\n\n\n\n<h2 style=\"text-align: justify;\">Tras los excesos navide\u00f1os, diez alimentos para incorporar definitivamente a tu dieta<\/h2>\n\n\n\n\n<p style=\"text-align: justify;\">La base de nuestra alimentaci\u00f3n debe ser verduras, frutas y en una proporci\u00f3n moderada carnes magras, pescados, huevos, l\u00e1cteos, desnatados, por supuesto, cereales integrales\u2026<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>1 &#8211; Las alcachofas<\/strong> nos pueden ayudar a disminuir esa hinchaz\u00f3n y mejorar las digestiones, reducir la formaci\u00f3n de gases y al mejorar las funciones hep\u00e1ticas, tambi\u00e9n puede ayudarnos a disminuir los niveles de colesterol. Sin olvidarnos de su acci\u00f3n diur\u00e9tica y depurativa. Para aprovechar mejor sus propiedades, hay que cocerlas y beber el agua de la cocci\u00f3n, que resulta muy diur\u00e9tica.\nPodemos elaborar un caldo depurativo y diur\u00e9tico a base de alcachofa, apio, puerro y cebolla y tomarnos un vaso antes de la comida y la cena. Adem\u00e1s actuar\u00e1 de manera saciante calmando nuestro apetito y disminuyendo la ingesta de comida.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>2 &#8211; Las espinacas<\/strong> nos aportaran mucha fibra, vitaminas del grupo B, Hierro, Yodo, Calcio y Clorofila. Nos dar\u00e1 mucha energ\u00eda sin casi aporte de Kcal (20kcal \/100g).<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>3 &#8211; <\/strong>Gracias a su alto contenido en fibra, <strong>la pi\u00f1a<\/strong>, puede sernos de gran ayuda. Actuar\u00e1 como saciante y reguladora del tr\u00e1nsito intestinal, adem\u00e1s, por su aporte de enzimas proteol\u00edticas conocidas como la <strong><a href=\"http:\/\/yomecuidoyque.com\/mejora-tu-digestion-con-pina-kiwi-y-papaya\/\" target=\"_blank\" rel=\"noopener\">bromelina o bromela\u00edna<\/a><\/strong>, mejorar\u00e1 nuestras digestiones.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>4 &#8211;<\/strong> <strong>Los esp\u00e1rragos<\/strong> son un refrescante natural del organismo. El 95% de su composici\u00f3n es agua. Son ricos en minerales como Potasio, F\u00f3sforo, Calcio, Magnesio y Cobre y vitaminas B1, C, A, E y \u00c1cido F\u00f3lico. Se caracterizan por ser depurativos, diur\u00e9ticos y laxantes por su alto contenido en fibra.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>5 &#8211;<\/strong> Las<strong> jud\u00edas verdes<\/strong> son ricas en vitaminas C, Hierro, Potasio, F\u00f3sforo y \u00c1cido F\u00f3lico. Adem\u00e1s, son muy digestivas y ayudan a regular los niveles de az\u00facar y colesterol en sangre.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>6 &#8211; <\/strong>Consumo de <strong>l\u00e1cteos desnatados<\/strong> que podemos tomarlos como postres, a media ma\u00f1ana o de merienda.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>7 &#8211; <\/strong>Debemos incluir en nuestra dieta unas 3 cucharadas de <strong>aceite de oliva,<\/strong> ya que es un alimento que tiene un gran poder antioxidante, contiene grandes nutrientes tales como la vitamina E, Carotenos, y Polifenoles.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>8 &#8211;<\/strong> Tampoco debemos olvidarnos de los <strong>hidratos de carbono<\/strong>, aunque es conveniente disminuir su consumo, no debemos eliminarlo por completo de nuestra alimentaci\u00f3n, ya que es nutriente indispensable para la vida. Cerebro y coraz\u00f3n necesitan de ellos para funcionar correctamente. Simplemente bastar\u00e1 con eliminar aquellos que denominamos simples, <a href=\"http:\/\/yomecuidoyque.com\/dime-como-te-endulzas-y-te-dire\/\" target=\"_blank\" rel=\"noopener\">az\u00facar blanco<\/a>, boller\u00eda industrial, y consumir hidratos de carbono complejos, como pueden ser, cereales integrales. Acompa\u00f1ar la comida y la cena con una rebanada de pan integral puede ser una buena alternativa.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>9 &#8211; <\/strong>Otra de las medidas es reducir el consumo de sal. Nuestro cuerpo necesita peque\u00f1as cantidades de sal, sodio, para que funcione adecuadamente. Un exceso de sal fuerza el trabajo de nuestros ri\u00f1ones, aumenta la retenci\u00f3n de l\u00edquidos y favorece el aumento de la tensi\u00f3n arterial. Para evitar la sal, una buena opci\u00f3n es potenciar tus platos con hierbas y <strong>especias ricas en nutrientes<\/strong> como la pimienta o la c\u00farcuma.<\/p>\n\n\n\n\n<p style=\"text-align: justify;\"><strong>10 &#8211;<\/strong> Y casi lo m\u00e1s importante de todo, <strong>el agua.<\/strong> Es important\u00edsimo beber la cantidad suficiente de agua, aproximadamente dos litros y medio diarios, increment\u00e1ndose esa cantidad si se hace deporte intenso. De esta manera, facilitamos al cuerpo la eliminaci\u00f3n de las toxinas, provocadas por los excesos, a trav\u00e9s de la orina. Si te resulta dif\u00edcil llegar a esa cantidad, puedes ayudarte tomando infusiones, como el t\u00e9 verde.<\/p>\n\n]]>    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adi\u00f3s excesos,\u00a0 bienvenida dieta sana Despu\u00e9s de los excesos navide\u00f1os, es normal sentir cierto malestar; hinchaz\u00f3n, empacho, diarrea, estre\u00f1imiento, dolor<\/p>\n","protected":false},"author":2,"featured_media":1619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[126,129],"tags":[],"class_list":["post-1596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-habitos-saludables","category-nutricion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English<\/title>\n<meta name=\"description\" content=\"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English\" \/>\n<meta property=\"og:description\" content=\"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi English\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T08:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nuria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/\"},\"author\":{\"name\":\"Nuria\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#\\\/schema\\\/person\\\/0540e70c77f6c6308596267b51fc57dc\"},\"headline\":\"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os\",\"datePublished\":\"2016-01-07T08:30:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/\"},\"wordCount\":807,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/01\\\/10-alimentos-frente-a-los-excesos-navidenos.jpg\",\"articleSection\":[\"H\u00e1bitos Saludables\",\"Nutrici\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/\",\"name\":\"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/01\\\/10-alimentos-frente-a-los-excesos-navidenos.jpg\",\"datePublished\":\"2016-01-07T08:30:26+00:00\",\"description\":\"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/01\\\/10-alimentos-frente-a-los-excesos-navidenos.jpg\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/01\\\/10-alimentos-frente-a-los-excesos-navidenos.jpg\",\"width\":850,\"height\":440,\"caption\":\"10 alimentos frente a los excesos navide\u00f1os\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/\",\"name\":\"Drasanvi English\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/en\\\/#\\\/schema\\\/person\\\/0540e70c77f6c6308596267b51fc57dc\",\"name\":\"Nuria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g\",\"caption\":\"Nuria\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English","description":"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/","og_locale":"en_US","og_type":"article","og_title":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English","og_description":"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie","og_url":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/","og_site_name":"Drasanvi English","article_published_time":"2016-01-07T08:30:26+00:00","og_image":[{"width":850,"height":440,"url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg","type":"image\/jpeg"}],"author":"Nuria","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#article","isPartOf":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/"},"author":{"name":"Nuria","@id":"https:\/\/drasanvi.com\/en\/#\/schema\/person\/0540e70c77f6c6308596267b51fc57dc"},"headline":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os","datePublished":"2016-01-07T08:30:26+00:00","mainEntityOfPage":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/"},"wordCount":807,"commentCount":1,"publisher":{"@id":"https:\/\/drasanvi.com\/en\/#organization"},"image":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#primaryimage"},"thumbnailUrl":"https:\/\/drasanvi.com\/en\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg","articleSection":["H\u00e1bitos Saludables","Nutrici\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/","url":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/","name":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os - Drasanvi English","isPartOf":{"@id":"https:\/\/drasanvi.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#primaryimage"},"image":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#primaryimage"},"thumbnailUrl":"https:\/\/drasanvi.com\/en\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg","datePublished":"2016-01-07T08:30:26+00:00","description":"Los excesos navide\u00f1os provocan malestar general, hinchaz\u00f3n y alg\u00fan kilo de m\u00e1s. Toma nota de estos alimentos saludables para empezar el a\u00f1o con buen pie","breadcrumb":{"@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#primaryimage","url":"https:\/\/drasanvi.com\/en\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg","contentUrl":"https:\/\/drasanvi.com\/en\/wp-content\/uploads\/sites\/3\/2016\/01\/10-alimentos-frente-a-los-excesos-navidenos.jpg","width":850,"height":440,"caption":"10 alimentos frente a los excesos navide\u00f1os"},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/en\/10-alimentos-que-no-pueden-faltar-en-tu-dieta-despues-de-los-excesos-navidenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/en\/"},{"@type":"ListItem","position":2,"name":"10 alimentos que no pueden faltar en tu dieta despu\u00e9s de los excesos navide\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/en\/#website","url":"https:\/\/drasanvi.com\/en\/","name":"Drasanvi English","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/en\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/drasanvi.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/3\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/3\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/drasanvi.com\/en\/#\/schema\/person\/0540e70c77f6c6308596267b51fc57dc","name":"Nuria","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85760e8e3727599ce0b35a971bd9c81c64679f000057684172cb773dd3648789?s=96&d=mm&r=g","caption":"Nuria"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/posts\/1596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/comments?post=1596"}],"version-history":[{"count":0,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/posts\/1596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/media\/1619"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/media?parent=1596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/categories?post=1596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/en\/wp-json\/wp\/v2\/tags?post=1596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}