{"id":24779,"date":"2024-10-15T17:00:05","date_gmt":"2024-10-15T15:00:05","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/?post_type=product&#038;p=24779"},"modified":"2024-10-16T01:00:04","modified_gmt":"2024-10-15T23:00:04","slug":"aceite-cbd-20-10-ml-drasanvi","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/","title":{"rendered":"Aceite CBD 20% 10 ml Drasanvi"},"content":{"rendered":"<p>Nuestro aceite de CBD 20% de espectro completo tiene la m&aacute;xima calidad y alta seguridad. Precisamente, utilizamos todos los componentes de cannabinoides y terpenos que se encuentran en la planta de c&aacute;&ntilde;amo, lo que se conoce como Full Spectrum. De esta manera, se aprovecha el 100% de las propiedades que nos aporta esta planta.<\/p>\n<p>Se obtiene de plantas europeas de c&aacute;&ntilde;amo, donde tanto cultivo, recolecci&oacute;n, extracci&oacute;n y llenado se someten a un estricto control de calidad.<\/p>\n<h2>Ingredientes<\/h2>\n<h2>Modo de uso<\/h2>\n<p>Aplicar 5-10 gotas, directamente, sobre la piel o mezclar con otro aceite. Uso seg&uacute;n necesidad.<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>10 ml<\/p>\n<h2>Advertencias<\/h2>\n<p>No apto para mujeres embarazadas ni en lactancia&nbsp;<\/p>\n<p>Mantener fuera del alcance de ni&ntilde;os<\/p>\n<p>Mantener en un lugar fresco y seco y protegido de la luz&nbsp;<\/p>\n<p>Contiene menos del 0,2% THC&nbsp;<\/p>\n<h2>Valores nutricionales<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro aceite de CBD 20% de espectro completo tiene la m&aacute;xima calidad y alta seguridad. Precisamente, utilizamos todos los componentes de cannabinoides y terpenos que se encuentran en la planta de c&aacute;&ntilde;amo, lo que se conoce como Full Spectrum. De esta manera, se aprovecha el 100% de las propiedades que nos aporta esta planta.<\/p>\n<p>Se obtiene de plantas europeas de c&aacute;&ntilde;amo, donde tanto cultivo, recolecci&oacute;n, extracci&oacute;n y llenado se someten a un estricto control de calidad.<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/032060912\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"inline_featured_image":false},"product_cat":[87],"product_tag":[],"class_list":["post-24779","product","type-product","status-publish","hentry","product_cat-acido-urico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Nuestro aceite de CBD 20% de espectro completo tiene la m&aacute;xima calidad y alta seguridad. Precisamente, utilizamos todos los componentes de cannabinoides y terpenos que se encuentran en la planta de c&aacute;&ntilde;amo, lo que se conoce como Full Spectrum. De esta manera, se aprovecha el 100% de las propiedades que nos aporta esta planta. Se obtiene de plantas europeas de c&aacute;&ntilde;amo, donde tanto cultivo, recolecci&oacute;n, extracci&oacute;n y llenado se someten a un estricto control de calidad.Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T23:00:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-cbd-20-10-ml-drasanvi\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-cbd-20-10-ml-drasanvi\\\/\",\"name\":\"Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"datePublished\":\"2024-10-15T15:00:05+00:00\",\"dateModified\":\"2024-10-15T23:00:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-cbd-20-10-ml-drasanvi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-cbd-20-10-ml-drasanvi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-cbd-20-10-ml-drasanvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aceite CBD 20% 10 ml Drasanvi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/","og_locale":"es_ES","og_type":"article","og_title":"Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica","og_description":"Nuestro aceite de CBD 20% de espectro completo tiene la m&aacute;xima calidad y alta seguridad. Precisamente, utilizamos todos los componentes de cannabinoides y terpenos que se encuentran en la planta de c&aacute;&ntilde;amo, lo que se conoce como Full Spectrum. De esta manera, se aprovecha el 100% de las propiedades que nos aporta esta planta. Se obtiene de plantas europeas de c&aacute;&ntilde;amo, donde tanto cultivo, recolecci&oacute;n, extracci&oacute;n y llenado se someten a un estricto control de calidad.Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2024-10-15T23:00:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/","url":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/","name":"Aceite CBD 20% 10 ml Drasanvi - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"datePublished":"2024-10-15T15:00:05+00:00","dateModified":"2024-10-15T23:00:04+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-cbd-20-10-ml-drasanvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Aceite CBD 20% 10 ml Drasanvi"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24779\/revisions"}],"predecessor-version":[{"id":24806,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24779\/revisions\/24806"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=24779"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=24779"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=24779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}