{"id":24772,"date":"2024-10-15T16:00:08","date_gmt":"2024-10-15T14:00:08","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/?post_type=product&#038;p=24772"},"modified":"2024-10-16T01:00:09","modified_gmt":"2024-10-15T23:00:09","slug":"mineral-citrato-magnesio-polvo-200g","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/","title":{"rendered":"Mineral Citrato Magnesio Polvo 200g"},"content":{"rendered":"<p>El Magnesio es un mineral esencial para el organismo, sin embargo, y debido al tipo de alimentaci&oacute;n,&nbsp; puede existir d&eacute;ficit del mismo sobre todo en deportistas. El Magnesio, entre otros, esta relacionado con el cansancio y la fatiga, el mantenimiento de huesos,&nbsp; la s&iacute;ntesis proteica normal y muy importante en la contracci&oacute;n muscular. Hemos elegido la mejor fuente de Magnesio -citrato de magnesio- que mejora la biodisponibilidad. El magnesio se puede obtener a trav&eacute;s de diferentes fuentes, las cuales se clasifican en org&aacute;nicas e inorganicas.&nbsp; Por su solubilidad y su indepenencia del PH del organismo, las fuentes org&aacute;nicas son las que mayor tasa de asimilacion por parte del organismo tiene.&nbsp;<\/p>\n<h2>Ingredientes<\/h2>\n<p>Citrato de magnesio<em>(Magnesio 15,7%)<\/em><\/p>\n<h2>Modo de uso<\/h2>\n<p>Disolver 2 cucharadas del producto en agua o zumo una vez al d&iacute;a. Tambi&eacute;n puede tomarse una cuchara dosificadora 2 veces al d&iacute;a&nbsp;<\/p>\n<p>Dosis diaria recomendada: 2 cucharadas dosificadoras 1,6 g<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>Envase de 200 g (7,09 o.z)<\/p>\n<h2>Advertencias<\/h2>\n<p>Completo alimenticio a base de magnesio.<\/p>\n<p>Los complementos alimenticios no deben utilizarse como sustituto de una dieta variada y equilibrada y un estilo de vida saludable. No superar la dosis diaria expresamente recomendada. Mantener fuera del alcance de los ni&ntilde;os m&aacute;s peque&ntilde;os. Conservar en un lugar fresco y seco.<\/p>\n<h2>Valores nutricionales<\/h2>\n<table>\n<tbody>\n<tr>\n<td>Dosis<\/td>\n<td>Cantidad de Magnesio\/d&iacute;a<\/td>\n<td>%VRN*<\/td>\n<\/tr>\n<tr>\n<td>1,6 g&nbsp;&nbsp;<\/td>\n<td>250 mg<\/td>\n<td>66,67 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*Valor de Referencia de Nutrientes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Magnesio es un mineral esencial para el organismo, sin embargo, y debido al tipo de alimentaci&oacute;n,&nbsp; puede existir d&eacute;ficit del mismo sobre todo en deportistas. El Magnesio, entre otros, esta relacionado con el cansancio y la fatiga, el mantenimiento de huesos,&nbsp; la s&iacute;ntesis proteica normal y muy importante en la contracci&oacute;n muscular. Hemos elegido la mejor fuente de Magnesio -citrato de magnesio- que mejora la biodisponibilidad. El magnesio se puede obtener a trav&eacute;s de diferentes fuentes, las cuales se clasifican en org&aacute;nicas e inorganicas.&nbsp; Por su solubilidad y su indepenencia del PH del organismo, las fuentes org&aacute;nicas son las que mayor tasa de asimilacion por parte del organismo tiene.&nbsp;<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/032057484\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"inline_featured_image":false},"product_cat":[87],"product_tag":[],"class_list":["post-24772","product","type-product","status-publish","hentry","product_cat-acido-urico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"El Magnesio es un mineral esencial para el organismo, sin embargo, y debido al tipo de alimentaci&oacute;n,&nbsp; puede existir d&eacute;ficit del mismo sobre todo en deportistas. El Magnesio, entre otros, esta relacionado con el cansancio y la fatiga, el mantenimiento de huesos,&nbsp; la s&iacute;ntesis proteica normal y muy importante en la contracci&oacute;n muscular. Hemos elegido la mejor fuente de Magnesio -citrato de magnesio- que mejora la biodisponibilidad. El magnesio se puede obtener a trav&eacute;s de diferentes fuentes, las cuales se clasifican en org&aacute;nicas e inorganicas.&nbsp; Por su solubilidad y su indepenencia del PH del organismo, las fuentes org&aacute;nicas son las que mayor tasa de asimilacion por parte del organismo tiene.&nbsp;Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T23:00:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/mineral-citrato-magnesio-polvo-200g\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/mineral-citrato-magnesio-polvo-200g\\\/\",\"name\":\"Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"datePublished\":\"2024-10-15T14:00:08+00:00\",\"dateModified\":\"2024-10-15T23:00:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/mineral-citrato-magnesio-polvo-200g\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/mineral-citrato-magnesio-polvo-200g\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/mineral-citrato-magnesio-polvo-200g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mineral Citrato Magnesio Polvo 200g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/","og_locale":"es_ES","og_type":"article","og_title":"Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica","og_description":"El Magnesio es un mineral esencial para el organismo, sin embargo, y debido al tipo de alimentaci&oacute;n,&nbsp; puede existir d&eacute;ficit del mismo sobre todo en deportistas. El Magnesio, entre otros, esta relacionado con el cansancio y la fatiga, el mantenimiento de huesos,&nbsp; la s&iacute;ntesis proteica normal y muy importante en la contracci&oacute;n muscular. Hemos elegido la mejor fuente de Magnesio -citrato de magnesio- que mejora la biodisponibilidad. El magnesio se puede obtener a trav&eacute;s de diferentes fuentes, las cuales se clasifican en org&aacute;nicas e inorganicas.&nbsp; Por su solubilidad y su indepenencia del PH del organismo, las fuentes org&aacute;nicas son las que mayor tasa de asimilacion por parte del organismo tiene.&nbsp;Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2024-10-15T23:00:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/","url":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/","name":"Mineral Citrato Magnesio Polvo 200g - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"datePublished":"2024-10-15T14:00:08+00:00","dateModified":"2024-10-15T23:00:09+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/mineral-citrato-magnesio-polvo-200g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Mineral Citrato Magnesio Polvo 200g"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24772\/revisions"}],"predecessor-version":[{"id":24797,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24772\/revisions\/24797"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=24772"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=24772"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=24772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}