{"id":24025,"date":"2023-02-21T20:00:07","date_gmt":"2023-02-21T18:00:07","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/?post_type=product&#038;p=24025"},"modified":"2024-10-15T01:00:04","modified_gmt":"2024-10-14T23:00:04","slug":"aceite-de-almendras-dulces-250-ml-drasanvi","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/","title":{"rendered":"Aceite de Almendras Dulces 250 ml Drasanvi"},"content":{"rendered":"<p>El Aceite de Almendras Dulces contiene una gran cantidad de<strong> &aacute;cidos grasos insaturados<\/strong>, lo que lo convierte en un aceite, especialmente, nutritivo e hidratante, tanto para la piel como para el cabello.Sus propiedades emolientes permiten suavizar la piel, reducir las arrugas y estr&iacute;as, as&iacute; como calmar irritaciones cut&aacute;neas o descamaciones. Esta indicado para todo tipo de pieles, incluso, para las m&aacute;s sensibles como la de los bebes.<\/p>\n<h2>Ingredientes<\/h2>\n<p><em>Prunus Amygdalus Dulcis Oil.<\/em><\/p>\n<h2>Modo de uso<\/h2>\n<p>El Aceite de Almendras Dulces es de aplicaci&oacute;n t&oacute;pica como calmante o emoliente. Tambi&eacute;n se utiliza para combatir la sequedad del cabello o para mezclar con otros aceites vegetales o esenciales.<\/p>\n<p><strong>Sobre la piel: <\/strong>Aplicar directamente sobre la piel (seca o h&uacute;meda) con un ligero masaje, hasta que se absorba.<\/p>\n<p><strong>Sobre el cabello:<\/strong> Aplicar con un suave masaje y dejar actuar durante 15 minutos. Aclarar con abundante agua.<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>Envase de 250 ml (8.45 fl oz)<\/p>\n<h2>Advertencias<\/h2>\n<p>No ingerir. Evitar el contacto con los ojos, heridas abiertas y mucosas. Mantener en un lugar fresco y seco&nbsp;<\/p>\n<h2>Valores nutricionales<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>El Aceite de Almendras Dulces contiene una gran cantidad de<strong> &aacute;cidos grasos insaturados<\/strong>, lo que lo convierte en un aceite, especialmente, nutritivo e hidratante, tanto para la piel como para el cabello.Sus propiedades emolientes permiten suavizar la piel, reducir las arrugas y estr&iacute;as, as&iacute; como calmar irritaciones cut&aacute;neas o descamaciones. Esta indicado para todo tipo de pieles, incluso, para las m&aacute;s sensibles como la de los bebes.<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/032060836\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"inline_featured_image":false},"product_cat":[87],"product_tag":[],"class_list":["post-24025","product","type-product","status-publish","hentry","product_cat-acido-urico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"El Aceite de Almendras Dulces contiene una gran cantidad de &aacute;cidos grasos insaturados, lo que lo convierte en un aceite, especialmente, nutritivo e hidratante, tanto para la piel como para el cabello.Sus propiedades emolientes permiten suavizar la piel, reducir las arrugas y estr&iacute;as, as&iacute; como calmar irritaciones cut&aacute;neas o descamaciones. Esta indicado para todo tipo de pieles, incluso, para las m&aacute;s sensibles como la de los bebes.Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T23:00:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-de-almendras-dulces-250-ml-drasanvi\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-de-almendras-dulces-250-ml-drasanvi\\\/\",\"name\":\"Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"datePublished\":\"2023-02-21T18:00:07+00:00\",\"dateModified\":\"2024-10-14T23:00:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-de-almendras-dulces-250-ml-drasanvi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-de-almendras-dulces-250-ml-drasanvi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/aceite-de-almendras-dulces-250-ml-drasanvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aceite de Almendras Dulces 250 ml Drasanvi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/","og_locale":"es_ES","og_type":"article","og_title":"Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica","og_description":"El Aceite de Almendras Dulces contiene una gran cantidad de &aacute;cidos grasos insaturados, lo que lo convierte en un aceite, especialmente, nutritivo e hidratante, tanto para la piel como para el cabello.Sus propiedades emolientes permiten suavizar la piel, reducir las arrugas y estr&iacute;as, as&iacute; como calmar irritaciones cut&aacute;neas o descamaciones. Esta indicado para todo tipo de pieles, incluso, para las m&aacute;s sensibles como la de los bebes.Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2024-10-14T23:00:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/","url":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/","name":"Aceite de Almendras Dulces 250 ml Drasanvi - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"datePublished":"2023-02-21T18:00:07+00:00","dateModified":"2024-10-14T23:00:04+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/aceite-de-almendras-dulces-250-ml-drasanvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Aceite de Almendras Dulces 250 ml Drasanvi"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24025\/revisions"}],"predecessor-version":[{"id":24610,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/24025\/revisions\/24610"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=24025"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=24025"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=24025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}