{"id":23479,"date":"2022-03-23T14:42:00","date_gmt":"2022-03-23T12:42:00","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/"},"modified":"2023-08-11T15:38:00","modified_gmt":"2023-08-11T13:38:00","slug":"cr-aceite-coco-virgen-bio-500ml-ecosana","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/","title":{"rendered":"Aceite de coco virgen extra 500 ml Ecosana"},"content":{"rendered":"<p>El Aceite de Coco Virgen Extra de ECOSANA es obtenido de cocos procedentes de agricultura ecol&oacute;gica. Estos han sido cultivados y recolectados de una manera respetuosa con el medio ambiente, consiguiendo un aceite con todo el sabor y las propiedades naturales del coco. El Aceite de coco es utilizado para cocinar, fre&iacute;r y hornear tus recetas gracias a que &eacute;ste, no se adultera ni se vuelve t&oacute;xico a altas temperaturas.<\/p>\n<h2>Ingredientes<\/h2>\n<p>Agricultura no UE<\/p>\n<p>Sin az&uacute;cares a&ntilde;adidos<\/p>\n<h2>Modo de uso<\/h2>\n<p>&Uacute;salo a tu gusto para cocinar &oacute; fre&iacute;r como sustituto de tu aceite convencional. Tambi&eacute;n puedes emplearlo en tus recetas favoritas de reposter&iacute;a.<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>Envase de 500 ml (452 g).<\/p>\n<h2>Advertencias<\/h2>\n<p>Conservar en un lugar fresco y seco.<\/p>\n<p>Libre de al&eacute;rgenos<\/p>\n<h2>Valores nutricionales<\/h2>\n<p>Por cada 100 g<\/p>\n<table>\n<tbody>\n<tr>\n<td><strong>Ingrediente<\/strong><\/td>\n<td><strong>Cantidad&nbsp;<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Valor energ&eacute;tico<\/strong><\/td>\n<td><strong>3660 kJ \/874,76 Kcal<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Grasas <\/strong><em>De las cuales saturadas <\/em><em>De las cuales monoinsaturadas <\/em><em>De las cuales poliinsaturadas<\/em><\/td>\n<td><strong>99,92 g<\/strong> <em>94,62 g 4,53<\/em> <em>g<\/em> <em>0,77 g<\/em><\/td>\n<\/tr>\n<tr>\n<td><strong>Hidratos de carbono <\/strong><em>De los cuales az&uacute;cares <\/em><\/td>\n<td><strong>0 g<\/strong> <em>0 g<\/em><\/td>\n<\/tr>\n<tr>\n<td><strong>Fibra <\/strong><\/td>\n<td><strong>0 g<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Prote&iacute;nas<\/strong><\/td>\n<td><strong>0,20 g<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Sal<\/strong><\/td>\n<td><strong>0,0022 g<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El Aceite de Coco Virgen Extra de ECOSANA es obtenido de cocos procedentes de agricultura ecol&oacute;gica. Estos han sido cultivados y recolectados de una manera respetuosa con el medio ambiente, consiguiendo un aceite con todo el sabor y las propiedades naturales del coco. El Aceite de coco es utilizado para cocinar, fre&iacute;r y hornear tus recetas gracias a que &eacute;ste, no se adultera ni se vuelve t&oacute;xico a altas temperaturas.<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/467010221\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":23677,"template":"","meta":{"inline_featured_image":false},"product_cat":[1406,1381,1407],"product_tag":[],"class_list":["post-23479","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-aceites","product_cat-alimentacion","product_cat-vinagres-y-condimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"El Aceite de Coco Virgen Extra de ECOSANA es obtenido de cocos procedentes de agricultura ecol&oacute;gica. Estos han sido cultivados y recolectados de una manera respetuosa con el medio ambiente, consiguiendo un aceite con todo el sabor y las propiedades naturales del coco. El Aceite de coco es utilizado para cocinar, fre&iacute;r y hornear tus recetas gracias a que &eacute;ste, no se adultera ni se vuelve t&oacute;xico a altas temperaturas.Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T13:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/467010221.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/\",\"name\":\"Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/467010221.png\",\"datePublished\":\"2022-03-23T12:42:00+00:00\",\"dateModified\":\"2023-08-11T13:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/467010221.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/467010221.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-aceite-coco-virgen-bio-500ml-ecosana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aceite de coco virgen extra 500 ml Ecosana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/","og_locale":"es_ES","og_type":"article","og_title":"Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica","og_description":"El Aceite de Coco Virgen Extra de ECOSANA es obtenido de cocos procedentes de agricultura ecol&oacute;gica. Estos han sido cultivados y recolectados de una manera respetuosa con el medio ambiente, consiguiendo un aceite con todo el sabor y las propiedades naturales del coco. El Aceite de coco es utilizado para cocinar, fre&iacute;r y hornear tus recetas gracias a que &eacute;ste, no se adultera ni se vuelve t&oacute;xico a altas temperaturas.Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2023-08-11T13:38:00+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/467010221.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/","url":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/","name":"Aceite de coco virgen extra 500 ml Ecosana - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/#primaryimage"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/#primaryimage"},"thumbnailUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/467010221.png","datePublished":"2022-03-23T12:42:00+00:00","dateModified":"2023-08-11T13:38:00+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/#primaryimage","url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/467010221.png","contentUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/467010221.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-aceite-coco-virgen-bio-500ml-ecosana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Aceite de coco virgen extra 500 ml Ecosana"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media\/23677"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=23479"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=23479"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=23479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}