{"id":23437,"date":"2022-03-23T14:42:25","date_gmt":"2022-03-23T12:42:25","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/"},"modified":"2024-10-16T01:00:06","modified_gmt":"2024-10-15T23:00:06","slug":"cr-mineral-citrato-potasio-90-comprimidos-drasanvi","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/","title":{"rendered":"Citrato de Potasio 90 Comprimidos Drasanvi"},"content":{"rendered":"<p>El potasio es un mineral esencial para nuestro cuerpo, por ello se ha seleccionado la forma de citrato, ya que aumenta la biodisponibilidad, por parte de nuestro organismo. Entre las funciones del potasio en nuestro organismo, destacar que contribuye al funcionamiento normal del sistema nervioso, contribuye al funcionamiento normal de los m&uacute;sculos y al mantenimiento de la tensi&oacute;n arterial normal.&nbsp;<\/p>\n<h2>Ingredientes<\/h2>\n<p>Citrato de potasio<em>(36% potasio)<\/em>1.111 mg, Agente de carga<em>(Celulosa microcristalina)<\/em>, Agente de carga<em>(Sal magn&eacute;sica de &aacute;cido graso)<\/em>, Antiaglomerante<em>(Di&oacute;xido de silicio)<\/em><\/p>\n<h2>Modo de uso<\/h2>\n<p>Tomar dos comprimidos al d&iacute;a repartidos en dos de las comidas principales.&nbsp;<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>90 comprimidos de 980.5 mg. Peso total 88.25g (3.11oz)<\/p>\n<h2>Advertencias<\/h2>\n<p>Complemento alimenticio a base de minerales. No superar la dosis diaria expresamente recomendada; Los complementos alimenticios no deben utilizarse como sustituto de una dieta equilibrada; Mantener fuera del alcance de los ni&ntilde;os m&aacute;s peque&ntilde;os. Conservar en un lugar fresco y seco.<\/p>\n<h2>Valores nutricionales<\/h2>\n<p>por dosis diaria (2 comprimidos)<\/p>\n<table>\n<tbody>\n<tr>\n<th>Ingrediente<\/th>\n<th>Porcentaje<\/th>\n<th>Cantidad<\/th>\n<\/tr>\n<tr>\n<td>Potasio<\/td>\n<td>20%<\/td>\n<td>400 mg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>% VRN (Valores de Referencia de Nutrientes)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El potasio es un mineral esencial para nuestro cuerpo, por ello se ha seleccionado la forma de citrato, ya que aumenta la biodisponibilidad, por parte de nuestro organismo. Entre las funciones del potasio en nuestro organismo, destacar que contribuye al funcionamiento normal del sistema nervioso, contribuye al funcionamiento normal de los m&uacute;sculos y al mantenimiento de la tensi&oacute;n arterial normal.&nbsp;<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/032057107\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":23439,"template":"","meta":{"inline_featured_image":false},"product_cat":[1383,1401],"product_tag":[],"class_list":["post-23437","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-complementos","product_cat-vitaminas-y-minerales","pa_contiene-altramuces-no","pa_contiene-apio-no","pa_contiene-cacahuetes-no","pa_contiene-crustaceos-no","pa_contiene-gluten-no","pa_contiene-huevo-no","pa_contiene-leche-no","pa_contiene-moluscos-no","pa_contiene-mostaza-no","pa_contiene-pescado-no","pa_contiene-sesamo-no","pa_contiene-soja-no","pa_producto-bio-no","pa_producto-vegano-si","pa_producto-vegetariano-no"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"El potasio es un mineral esencial para nuestro cuerpo, por ello se ha seleccionado la forma de citrato, ya que aumenta la biodisponibilidad, por parte de nuestro organismo. Entre las funciones del potasio en nuestro organismo, destacar que contribuye al funcionamiento normal del sistema nervioso, contribuye al funcionamiento normal de los m&uacute;sculos y al mantenimiento de la tensi&oacute;n arterial normal.&nbsp;Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T23:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032057107.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/\",\"name\":\"Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032057107.png\",\"datePublished\":\"2022-03-23T12:42:25+00:00\",\"dateModified\":\"2024-10-15T23:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032057107.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032057107.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Citrato de Potasio 90 Comprimidos Drasanvi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/","og_locale":"es_ES","og_type":"article","og_title":"Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica","og_description":"El potasio es un mineral esencial para nuestro cuerpo, por ello se ha seleccionado la forma de citrato, ya que aumenta la biodisponibilidad, por parte de nuestro organismo. Entre las funciones del potasio en nuestro organismo, destacar que contribuye al funcionamiento normal del sistema nervioso, contribuye al funcionamiento normal de los m&uacute;sculos y al mantenimiento de la tensi&oacute;n arterial normal.&nbsp;Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2024-10-15T23:00:06+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032057107.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/","url":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/","name":"Citrato de Potasio 90 Comprimidos Drasanvi - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/#primaryimage"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/#primaryimage"},"thumbnailUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032057107.png","datePublished":"2022-03-23T12:42:25+00:00","dateModified":"2024-10-15T23:00:06+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/#primaryimage","url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032057107.png","contentUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032057107.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-mineral-citrato-potasio-90-comprimidos-drasanvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Citrato de Potasio 90 Comprimidos Drasanvi"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23437\/revisions"}],"predecessor-version":[{"id":24639,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23437\/revisions\/24639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media\/23439"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=23437"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=23437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=23437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}