{"id":23410,"date":"2022-03-23T14:41:34","date_gmt":"2022-03-23T12:41:34","guid":{"rendered":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/"},"modified":"2024-10-16T01:00:05","modified_gmt":"2024-10-15T23:00:05","slug":"cr-bronze-30-perlas-drasanvi","status":"publish","type":"product","link":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/","title":{"rendered":"Bronze 30 perlas Drasanvi"},"content":{"rendered":"<p>Bronze Natural es un complemento alimenticio a base de aceite de Rosade Mosqueta, rica en &aacute;cidos grasos esenciales, extracto seco de Tomate,Zanahoria y Alga Dunaliella, extractos ricos en pigmentos como elLicopeno, Betacarotenos y Lute&iacute;na. Adem&aacute;s, incorpora una fuente deVitaminas (A, E, C y B2), destacando la Vitamina E, que contribuye a laprotecci&oacute;n de las c&eacute;lulas frente al da&ntilde;o oxidativo. Por su importancia,mencionar la presencia del amino&aacute;cido L-tirosina, precursor de laMelanina (pigmento responsable del color de la piel).<\/p>\n<h2>Ingredientes<\/h2>\n<p><b style=\"text-decoration: underline\">Envoltura<\/b><em>(Gelatina de Pescado, Glicerina, Cardurin Orange Ambar, Cardurin Silver Lustre)<\/em>, Aceite Rosa Mosqueta<em>(Rosa Aff Rubiginosa)<\/em>170 mg, L-Tirosina<em>&nbsp;<\/em>100 mg, Aceite de Girasol<em>(Helianthus annuus L.)<\/em>100 mg, Vitamina C<em>(82.16% &Aacute;cido asc&oacute;rbico)<\/em>58,9 mg, Sultato de Hierro<em>(Hierro 32,94%)<\/em>21,25 mg, Extracto seco de Tomate<em>(Solanum lycopersicum L.)<\/em>18 mg, Extracto seco de Zanahoria<em>(Daucus carota L., )<\/em>18 mg, Tomate<em>(Solanum lycopersicum L. Licopeno 6%)<\/em>18 mg, Extracto seco de Alga Dunaliella<em>(Dunaliella salina, Betacaroteno 20%)<\/em>18 mg, Lute&iacute;na<em>&nbsp;<\/em>16 mg, <b style=\"text-decoration: underline\">Aceite de Soja<\/b><em>(Glycine max (L) Merr)<\/em>15 mg, Sulfato de Zinc<em>(Zinc 36,44%)<\/em>13,72 mg, Vitamina E<em>(67% D-alfa-tocoferol)<\/em>8,95 mg, Vitamina A<em>(Palminato de retinol)<\/em>1,34 mg, Vitamina B2<em>(Riboflavina)<\/em>0,7 mg, Cloruro de Cromo<em>(19.5% Cromo)<\/em>0,11 mg, Di&oacute;xido de Silicio<em>(Antiaglomerante)<\/em><\/p>\n<h2>Modo de uso<\/h2>\n<p>Una perla al d&iacute;a, <strong>antes, durante y despu&eacute;s de los meses de exposici&oacute;n<\/strong> del sol. Se recomienda empezar un mes antes de comenzar, y prolongar la toma hasta un mes despu&eacute;s.Contiene soja y fuente de pescado.<\/p>\n<h2>Presentaci\u00f3n<\/h2>\n<p>Envase de 30 perlas de 780 mg. Peso total: 23,4 g (0.82 oz)<\/p>\n<h2>Advertencias<\/h2>\n<p>Los complementos alimenticios no deben utilizarse como sustitutivos de una dieta equilibrada y un modo de vida sano. No superar la dosis diaria recomendada.Mantener fuera del alcance de los ni&ntilde;os. Conservar en un lugar fresco y seco.<\/p>\n<p>Contiene pescado, contiene soja.<\/p>\n<h2>Valores nutricionales<\/h2>\n<p>Por dosis diaria (1 perla)<\/p>\n<table>\n<tbody>\n<tr>\n<td>Ingrediente<\/td>\n<td>Porcentaje<\/td>\n<td>Cantidad<\/td>\n<\/tr>\n<tr>\n<td>Vitamina C<\/td>\n<td>60.5%<\/td>\n<td>48.40 mg<\/td>\n<\/tr>\n<tr>\n<td>Hierro<\/td>\n<td>50%<\/td>\n<td>7 mg<\/td>\n<\/tr>\n<tr>\n<td>Zinc<\/td>\n<td>50%<\/td>\n<td>5 mg<\/td>\n<\/tr>\n<tr>\n<td>Vitamina E<\/td>\n<td>50%<\/td>\n<td>6 mg<\/td>\n<\/tr>\n<tr>\n<td>Vitamina A<\/td>\n<td>50%<\/td>\n<td>400 &micro;g<\/td>\n<\/tr>\n<tr>\n<td>Vitamina B2<\/td>\n<td>50%<\/td>\n<td>0,7 mg<\/td>\n<\/tr>\n<tr>\n<td>Cromo<\/td>\n<td>50%<\/td>\n<td>20 ?g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>% CDR (Cantidad Diaria Recomendada)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bronze Natural es un complemento alimenticio a base de aceite de Rosade Mosqueta, rica en &aacute;cidos grasos esenciales, extracto seco de Tomate,Zanahoria y Alga Dunaliella, extractos ricos en pigmentos como elLicopeno, Betacarotenos y Lute&iacute;na. Adem&aacute;s, incorpora una fuente deVitaminas (A, E, C y B2), destacando la Vitamina E, que contribuye a laprotecci&oacute;n de las c&eacute;lulas frente al da&ntilde;o oxidativo. Por su importancia,mencionar la presencia del amino&aacute;cido L-tirosina, precursor de laMelanina (pigmento responsable del color de la piel).<\/p>\n<p><a id=\"boton-ficha\" href=\"https:\/\/panel.drasanvi.com\/fichas\/3\/032050425\">Ficha t\u00e9cnica<\/a><\/p>\n","protected":false},"featured_media":23412,"template":"","meta":{"inline_featured_image":false},"product_cat":[1385,1383,1386],"product_tag":[],"class_list":["post-23410","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-cabello","product_cat-complementos","product_cat-piel-y-unas","pa_contiene-altramuces-no","pa_contiene-apio-no","pa_contiene-cacahuetes-no","pa_contiene-crustaceos-no","pa_contiene-gluten-no","pa_contiene-huevo-no","pa_contiene-leche-no","pa_contiene-moluscos-no","pa_contiene-mostaza-no","pa_contiene-pescado-si","pa_contiene-sesamo-no","pa_contiene-soja-si","pa_producto-bio-no","pa_producto-vegano-no","pa_producto-vegetariano-no"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bronze 30 perlas Drasanvi - Drasanvi Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bronze 30 perlas Drasanvi - Drasanvi Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Bronze Natural es un complemento alimenticio a base de aceite de Rosade Mosqueta, rica en &aacute;cidos grasos esenciales, extracto seco de Tomate,Zanahoria y Alga Dunaliella, extractos ricos en pigmentos como elLicopeno, Betacarotenos y Lute&iacute;na. Adem&aacute;s, incorpora una fuente deVitaminas (A, E, C y B2), destacando la Vitamina E, que contribuye a laprotecci&oacute;n de las c&eacute;lulas frente al da&ntilde;o oxidativo. Por su importancia,mencionar la presencia del amino&aacute;cido L-tirosina, precursor de laMelanina (pigmento responsable del color de la piel).Ficha t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Drasanvi Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T23:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032050425.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/\",\"name\":\"Bronze 30 perlas Drasanvi - Drasanvi Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032050425.png\",\"datePublished\":\"2022-03-23T12:41:34+00:00\",\"dateModified\":\"2024-10-15T23:00:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032050425.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/032050425.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/producto\\\/cr-bronze-30-perlas-drasanvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bronze 30 perlas Drasanvi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#website\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"name\":\"Drasanvi Costa Rica\",\"description\":\"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#organization\",\"name\":\"Drasanvi\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"contentUrl\":\"https:\\\/\\\/drasanvi.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/logo-drasanvi.png\",\"width\":900,\"height\":300,\"caption\":\"Drasanvi\"},\"image\":{\"@id\":\"https:\\\/\\\/drasanvi.com\\\/cr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bronze 30 perlas Drasanvi - Drasanvi Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/","og_locale":"es_ES","og_type":"article","og_title":"Bronze 30 perlas Drasanvi - Drasanvi Costa Rica","og_description":"Bronze Natural es un complemento alimenticio a base de aceite de Rosade Mosqueta, rica en &aacute;cidos grasos esenciales, extracto seco de Tomate,Zanahoria y Alga Dunaliella, extractos ricos en pigmentos como elLicopeno, Betacarotenos y Lute&iacute;na. Adem&aacute;s, incorpora una fuente deVitaminas (A, E, C y B2), destacando la Vitamina E, que contribuye a laprotecci&oacute;n de las c&eacute;lulas frente al da&ntilde;o oxidativo. Por su importancia,mencionar la presencia del amino&aacute;cido L-tirosina, precursor de laMelanina (pigmento responsable del color de la piel).Ficha t\u00e9cnica","og_url":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/","og_site_name":"Drasanvi Costa Rica","article_modified_time":"2024-10-15T23:00:05+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032050425.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/","url":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/","name":"Bronze 30 perlas Drasanvi - Drasanvi Costa Rica","isPartOf":{"@id":"https:\/\/drasanvi.com\/cr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/#primaryimage"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/#primaryimage"},"thumbnailUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032050425.png","datePublished":"2022-03-23T12:41:34+00:00","dateModified":"2024-10-15T23:00:05+00:00","breadcrumb":{"@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/#primaryimage","url":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032050425.png","contentUrl":"https:\/\/drasanvi.com\/cr\/wp-content\/uploads\/sites\/2\/2022\/03\/032050425.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/drasanvi.com\/cr\/producto\/cr-bronze-30-perlas-drasanvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drasanvi.com\/cr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/drasanvi.com\/cr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Bronze 30 perlas Drasanvi"}]},{"@type":"WebSite","@id":"https:\/\/drasanvi.com\/cr\/#website","url":"https:\/\/drasanvi.com\/cr\/","name":"Drasanvi Costa Rica","description":"L\u00edder en complementos alimenticios y cosm\u00e9tica natural.","publisher":{"@id":"https:\/\/drasanvi.com\/cr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drasanvi.com\/cr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drasanvi.com\/cr\/#organization","name":"Drasanvi","url":"https:\/\/drasanvi.com\/cr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/","url":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","contentUrl":"https:\/\/drasanvi.com\/wp-content\/uploads\/sites\/2\/2021\/07\/logo-drasanvi.png","width":900,"height":300,"caption":"Drasanvi"},"image":{"@id":"https:\/\/drasanvi.com\/cr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23410\/revisions"}],"predecessor-version":[{"id":24633,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product\/23410\/revisions\/24633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media\/23412"}],"wp:attachment":[{"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/media?parent=23410"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_cat?post=23410"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/drasanvi.com\/cr\/wp-json\/wp\/v2\/product_tag?post=23410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}